{"id":24181,"date":"2024-12-04T22:08:10","date_gmt":"2024-12-04T21:08:10","guid":{"rendered":"https:\/\/creanovaschool.com\/?p=24181"},"modified":"2024-12-04T22:08:10","modified_gmt":"2024-12-04T21:08:10","slug":"afa-creanova-families-que-sumem","status":"publish","type":"post","link":"https:\/\/creanovaschool.com\/ca\/2024\/afa-creanova-families-que-sumem\/","title":{"rendered":"AFA CreaNova: fam\u00edlies que sumem"},"content":{"rendered":"<p><em>AFA CreaNova<\/em> \u00e9s el pont entre les fam\u00edlies i el col\u00b7legi, amb diferents projectes que fomentin el sentit de comunitat del centre.<\/p>\n\n\n\n<p><em>AFA CreaNova<\/em>, l&#039;Associaci\u00f3 de Fam\u00edlies d&#039;Alumnes del col\u00b7legi, treballem de la m\u00e0 amb l&#039;escola per contribuir a fer que els nostres fills tinguin la millor experi\u00e8ncia educativa possible. Som el pont entre les fam\u00edlies i l&#039;escola, assegurant-nos que sempre hi hagi una comunicaci\u00f3 fluida i efectiva.<\/p>\n\n\n\n<p><strong>Qu\u00e8 fem?<\/strong><br>Comunicaci\u00f3 i interlocuci\u00f3 amb l&#039;escola, activitats l\u00fadiques i solid\u00e0ries, donar suport a la biblioteca ia la benvinguda a noves fam\u00edlies, tallers educatius\u2026 A <em>AFA<\/em>, duem a terme diferents iniciatives per fer costat tant als alumnes com a les seves fam\u00edlies.<\/p>\n\n\n\n<p>Ens reunim regularment amb la direcci\u00f3 i la ger\u00e8ncia del col\u00b7legi per parlar sobre qualsevol necessitat o suggeriment que sorgeixi, i per assegurar-nos que estem alineats en com millorar l&#039;entorn educatiu. A m\u00e9s, organitzem activitats que enriqueixen la vida escolar i creen un sentit de comunitat entre tots nosaltres.<\/p>\n\n\n\n<p><strong>Projectes destacats<\/strong><br>Un dels nostres projectes m\u00e9s emocionants \u00e9s la col\u00b7laboraci\u00f3 amb la Fundaci\u00f3 Vicente Ferrer que es va comen\u00e7ar el curs passat: estem treballant junts per construir una escola a Kotakonda (l&#039;\u00cdndia), la qual cosa permetr\u00e0 que molts nens i nenes accedisquen a una educaci\u00f3 de qualitat. El curs passat, aconseguirem recaptar gaireb\u00e9 1.000 euros i apadrinar 14 nens.<\/p>\n\n\n\n<p><strong>Projectes per a 2024-2025<\/strong><br>Per aquest curs 2024-2025 hem organitzat diverses activitats, com mercats ambulants, carrers ben\u00e8fics i tallers educatius sobre la cultura i les necessitats de la regi\u00f3 on es construir\u00e0 l&#039;escola, entre d&#039;altres. Aquestes iniciatives volen continuar recaptant fons solidaris.<\/p>\n\n\n\n<p>Un altre dels nostres eixos prioritaris ser\u00e0 l&#039;organitzaci\u00f3 de tallers orientats a fam\u00edlies i alumnes que abastin temes com la sexualitat o l&#039;assetjament a les xarxes. Tamb\u00e9, com a novetat, des de la comissi\u00f3 de benvinguda volem impulsar trobades i excursions per fomentar moments de trobada i passar-ho genial!<\/p>\n\n\n\n<p><strong>Com pots contribuir-hi?<\/strong><br>Amb tan sols 30\u20ac anuals per fam\u00edlia, aconseguim que grans coses succeeixin. Inscriu-te a <em>AFA<\/em> a trav\u00e9s de la nostra web <a href=\"http:\/\/www.afacreanova.org\">www.afacreanova.org<\/a>.<\/p>\n\n\n\n<p>Tamb\u00e9 pots implicar-te com a voluntari en esdeveniments o sumar-te a alguna de les comissions. Contacta&#039;ns a <a href=\"mailto:info@afacreanova.org\">info@afacreanova.org<\/a>. Cada aportaci\u00f3 compta i junts podem fer grans coses per a la comunitat escolar.<\/p>\n\n\n\n<p>Segueix-nos a Instagram: @afacreanova.<\/p>","protected":false},"excerpt":{"rendered":"<p>AFA CreaNova \u00e9s el pont entre les fam\u00edlies i el col\u00b7legi, amb diferents projectes que fomenten el sentit de comunitat del centre. AFA CreaNova, l&#8217;Associaci\u00f3 de Fam\u00edlies d&#8217;Alumnes del col\u00b7legi, treballem de la m\u00e0 amb l&#8217;escola per contribuir al fet que els nostres fills tinguin la millor experi\u00e8ncia educativa possible. Som el pont entre les [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1537],"tags":[1556],"class_list":["post-24181","post","type-post","status-publish","format-standard","hentry","category-revista","tag-r2-p14-cat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFA CreaNova: fam\u00edlies que sumem - CreaNova School<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/creanovaschool.com\/ca\/2024\/afa-creanova-families-que-sumem\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFA CreaNova: fam\u00edlies que sumem - CreaNova School\" \/>\n<meta property=\"og:description\" content=\"AFA CreaNova \u00e9s el pont entre les fam\u00edlies i el col\u00b7legi, amb diferents projectes que fomenten el sentit de comunitat del centre. AFA CreaNova, l&#8217;Associaci\u00f3 de Fam\u00edlies d&#8217;Alumnes del col\u00b7legi, treballem de la m\u00e0 amb l&#8217;escola per contribuir al fet que els nostres fills tinguin la millor experi\u00e8ncia educativa possible. Som el pont entre les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/creanovaschool.com\/ca\/2024\/afa-creanova-families-que-sumem\/\" \/>\n<meta property=\"og:site_name\" content=\"CreaNova School\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/collegi.creanova\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-04T21:08:10+00:00\" \/>\n<meta name=\"author\" content=\"EMAS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CollegiCreaNova\" \/>\n<meta name=\"twitter:site\" content=\"@CollegiCreaNova\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"EMAS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/\"},\"author\":{\"name\":\"EMAS\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#\\\/schema\\\/person\\\/bc31e364c1750c127046608ad51279e7\"},\"headline\":\"AFA CreaNova: fam\u00edlies que sumem\",\"datePublished\":\"2024-12-04T21:08:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/\"},\"wordCount\":411,\"publisher\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#organization\"},\"keywords\":[\"R2-P14-CAT\"],\"articleSection\":[\"Revista\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/\",\"url\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/\",\"name\":\"AFA CreaNova: fam\u00edlies que sumem - CreaNova School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#website\"},\"datePublished\":\"2024-12-04T21:08:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/2024\\\/afa-creanova-families-que-sumem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/creanovaschool.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFA CreaNova: fam\u00edlies que sumem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#website\",\"url\":\"https:\\\/\\\/creanovaschool.com\\\/\",\"name\":\"CreaNova School\",\"description\":\"Learning by doing private school in Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/creanovaschool.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#organization\",\"name\":\"CreaNova School\",\"url\":\"https:\\\/\\\/creanovaschool.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/creanovaschool.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo_Creanova_claim.png\",\"contentUrl\":\"https:\\\/\\\/creanovaschool.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo_Creanova_claim.png\",\"width\":2909,\"height\":960,\"caption\":\"CreaNova School\"},\"image\":{\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/collegi.creanova\",\"https:\\\/\\\/x.com\\\/CollegiCreaNova\",\"https:\\\/\\\/www.instagram.com\\\/collegicreanova\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/collegiCreaNova\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCNAWIuULmSWS1gnVCYmnIIw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/creanovaschool.com\\\/#\\\/schema\\\/person\\\/bc31e364c1750c127046608ad51279e7\",\"name\":\"EMAS\",\"url\":\"https:\\\/\\\/creanovaschool.com\\\/ca\\\/author\\\/nestor-silvaemas-es\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFA CreaNova: fam\u00edlies que sumem - CreaNova School","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/creanovaschool.com\/ca\/2024\/afa-creanova-families-que-sumem\/","og_locale":"ca_ES","og_type":"article","og_title":"AFA CreaNova: fam\u00edlies que sumem - CreaNova School","og_description":"AFA CreaNova \u00e9s el pont entre les fam\u00edlies i el col\u00b7legi, amb diferents projectes que fomenten el sentit de comunitat del centre. AFA CreaNova, l&#8217;Associaci\u00f3 de Fam\u00edlies d&#8217;Alumnes del col\u00b7legi, treballem de la m\u00e0 amb l&#8217;escola per contribuir al fet que els nostres fills tinguin la millor experi\u00e8ncia educativa possible. Som el pont entre les [&hellip;]","og_url":"https:\/\/creanovaschool.com\/ca\/2024\/afa-creanova-families-que-sumem\/","og_site_name":"CreaNova School","article_publisher":"https:\/\/www.facebook.com\/collegi.creanova","article_published_time":"2024-12-04T21:08:10+00:00","author":"EMAS","twitter_card":"summary_large_image","twitter_creator":"@CollegiCreaNova","twitter_site":"@CollegiCreaNova","twitter_misc":{"Escrit per":"EMAS","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/#article","isPartOf":{"@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/"},"author":{"name":"EMAS","@id":"https:\/\/creanovaschool.com\/#\/schema\/person\/bc31e364c1750c127046608ad51279e7"},"headline":"AFA CreaNova: fam\u00edlies que sumem","datePublished":"2024-12-04T21:08:10+00:00","mainEntityOfPage":{"@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/"},"wordCount":411,"publisher":{"@id":"https:\/\/creanovaschool.com\/#organization"},"keywords":["R2-P14-CAT"],"articleSection":["Revista"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/","url":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/","name":"AFA CreaNova: fam\u00edlies que sumem - CreaNova School","isPartOf":{"@id":"https:\/\/creanovaschool.com\/#website"},"datePublished":"2024-12-04T21:08:10+00:00","breadcrumb":{"@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/creanovaschool.com\/2024\/afa-creanova-families-que-sumem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/creanovaschool.com\/"},{"@type":"ListItem","position":2,"name":"AFA CreaNova: fam\u00edlies que sumem"}]},{"@type":"WebSite","@id":"https:\/\/creanovaschool.com\/#website","url":"https:\/\/creanovaschool.com\/","name":"CreaNova School","description":"Learning by doing private school in Barcelona","publisher":{"@id":"https:\/\/creanovaschool.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/creanovaschool.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/creanovaschool.com\/#organization","name":"CreaNova School","url":"https:\/\/creanovaschool.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/creanovaschool.com\/#\/schema\/logo\/image\/","url":"https:\/\/creanovaschool.com\/wp-content\/uploads\/2024\/07\/Logo_Creanova_claim.png","contentUrl":"https:\/\/creanovaschool.com\/wp-content\/uploads\/2024\/07\/Logo_Creanova_claim.png","width":2909,"height":960,"caption":"CreaNova School"},"image":{"@id":"https:\/\/creanovaschool.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/collegi.creanova","https:\/\/x.com\/CollegiCreaNova","https:\/\/www.instagram.com\/collegicreanova\/","https:\/\/www.pinterest.com\/collegiCreaNova\/","https:\/\/www.youtube.com\/channel\/UCNAWIuULmSWS1gnVCYmnIIw"]},{"@type":"Person","@id":"https:\/\/creanovaschool.com\/#\/schema\/person\/bc31e364c1750c127046608ad51279e7","name":"EMAS","url":"https:\/\/creanovaschool.com\/ca\/author\/nestor-silvaemas-es\/"}]}},"_links":{"self":[{"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/posts\/24181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/comments?post=24181"}],"version-history":[{"count":1,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/posts\/24181\/revisions"}],"predecessor-version":[{"id":24182,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/posts\/24181\/revisions\/24182"}],"wp:attachment":[{"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/media?parent=24181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/categories?post=24181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/creanovaschool.com\/ca\/wp-json\/wp\/v2\/tags?post=24181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}